{"id":2886,"date":"2025-06-19T19:42:03","date_gmt":"2025-06-19T11:42:03","guid":{"rendered":"https:\/\/www.ledphotometer.com\/blog\/gauge-for-outlets-16a-250v-a-c-of-iec-60906-1-figure-2\/"},"modified":"2025-06-19T19:42:03","modified_gmt":"2025-06-19T11:42:03","slug":"calibre-para-tomacorrientes-16a-250v-ca-de-iec-60906-1-figura-2","status":"publish","type":"post","link":"https:\/\/ledtestsystem.com\/es\/productos\/calibre-para-tomacorrientes-16a-250v-ca-de-iec-60906-1-figura-2\/","title":{"rendered":"Calibre para tomacorrientes de 16 A 250 V CA seg\u00fan IEC 60906-1 Figura 2"},"content":{"rendered":"<p>Durante las pruebas realizadas con estos medidores, las persianas deber\u00e1n permanecer abiertas.<\/p>\n<p>Las partes met\u00e1licas de los indicadores A, B y C est\u00e1n fabricadas con un metal duro y resistente a la corrosi\u00f3n (por ejemplo, acero inoxidable).<\/p>\n<p>Para indicar el contacto se utiliza un indicador el\u00e9ctrico con una tensi\u00f3n no inferior a 40 V ni superior a 50 V.<\/p>\n<p>El calibre A deber\u00e1 introducirse a trav\u00e9s de los orificios de entrada del conjunto de contacto del z\u00f3calo en todas las posiciones posibles hasta que el plano XX est\u00e9 completamente en contacto con la superficie de acoplamiento.<\/p>\n<p>El indicador no se encender\u00e1.<\/p>\n<p>Los pasadores de los calibres B y C deber\u00e1n insertarse completamente. Luego,<br \/>\n\u2013 para el indicador B, el indicador deber\u00e1 encenderse;<br \/>\n\u2013 Para el indicador C, el indicador no se encender\u00e1.<\/p>\n<div id=\"attachment_15355\" style=\"width: 672px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" aria-describedby=\"caption-attachment-15355\" decoding=\"async\" class=\"wp-image-15355 size-full\" src=\"https:\/\/www.lisungroup.com\/wp-content\/uploads\/2024\/09\/IEC-60906-1-Figure-2-1.png\" alt=\"\" width=\"662\" height=\"602\" srcset=\"https:\/\/www.lisungroup.com\/wp-content\/uploads\/2024\/09\/IEC-60906-1-Figure-2-1.png 662w, https:\/\/www.lisungroup.com\/wp-content\/uploads\/2024\/09\/IEC-60906-1-Figure-2-1-400x364.png 400w\" sizes=\"auto, (max-width: 662px) 100vw, 662px\" title=\"\"><\/p>\n<p id=\"caption-attachment-15355\" class=\"wp-caption-text\"><span style=\"color: #ff0000;\">IEC 60906-1 Figura 2<\/span><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>During the tests using these gauges, shutters shall be held open. The metallic parts of gauges A, B and C are made of hard corrosion-resistant metal (e.g. stainless steel). An electrical indicator with a voltage not less than 40V and not more than 50 V is used to show contact. The gauge A shall be [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[580],"class_list":["post-2886","post","type-post","status-publish","format-standard","hentry","category-products","tag-gngpl-90602"],"_links":{"self":[{"href":"https:\/\/ledtestsystem.com\/es\/wp-json\/wp\/v2\/posts\/2886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ledtestsystem.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ledtestsystem.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ledtestsystem.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ledtestsystem.com\/es\/wp-json\/wp\/v2\/comments?post=2886"}],"version-history":[{"count":0,"href":"https:\/\/ledtestsystem.com\/es\/wp-json\/wp\/v2\/posts\/2886\/revisions"}],"wp:attachment":[{"href":"https:\/\/ledtestsystem.com\/es\/wp-json\/wp\/v2\/media?parent=2886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ledtestsystem.com\/es\/wp-json\/wp\/v2\/categories?post=2886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ledtestsystem.com\/es\/wp-json\/wp\/v2\/tags?post=2886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}